{"id":16512,"date":"2026-05-13T03:01:19","date_gmt":"2026-05-13T03:01:19","guid":{"rendered":"https:\/\/www.coloriwatches.com\/product\/kids-watch-with-toucans\/"},"modified":"2026-05-13T03:02:15","modified_gmt":"2026-05-13T03:02:15","slug":"kids-watch-with-toucans","status":"publish","type":"product","link":"https:\/\/www.coloriwatches.com\/es\/producto\/kids-watch-with-toucans\/","title":{"rendered":"Reloj infantil con tucanes"},"content":{"rendered":"<p>Un reloj beige para ni\u00f1os con tucanes en la esfera. Este reloj es resistente al agua 5ATM. Para garantizar la longevidad del reloj, le aconsejamos que no lo lleve mientras nada. Es un reloj perfecto para que los ni\u00f1os aprendan a leer la hora.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un reloj beige para ni\u00f1os con tucanes en la esfera. Este reloj es resistente al agua 5ATM. Para garantizar la longevidad del reloj, le aconsejamos que no lo lleve mientras nada. Es un reloj perfecto para que los ni\u00f1os aprendan a leer la hora.<\/p>","protected":false},"featured_media":21331,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[51],"product_tag":[25],"class_list":{"0":"post-16512","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animals","7":"product_tag-sale","8":"pa_color-brown","9":"pa_ean13-62","11":"first","12":"instock","13":"sale","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/product\/16512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/comments?post=16512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/media\/21331"}],"wp:attachment":[{"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/media?parent=16512"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/product_brand?post=16512"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/product_cat?post=16512"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.coloriwatches.com\/es\/wp-json\/wp\/v2\/product_tag?post=16512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}